{"id":537,"date":"2025-12-23T20:24:07","date_gmt":"2025-12-23T12:24:07","guid":{"rendered":"https:\/\/www.goldminingmachine.com\/?p=537"},"modified":"2025-12-23T21:15:19","modified_gmt":"2025-12-23T13:15:19","slug":"vibrating-screen-gold-mining-machine","status":"publish","type":"post","link":"https:\/\/www.goldminingmachine.com\/es\/vibrating-screen-gold-mining-machine\/","title":{"rendered":"M\u00e1quina de miner\u00eda de oro de pantalla vibrante"},"content":{"rendered":"<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-546\" src=\"http:\/\/www.goldminingmachine.com\/wp-content\/uploads\/2025\/12\/Vibrating-Screen3.webp\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.goldminingmachine.com\/wp-content\/uploads\/2025\/12\/Vibrating-Screen3.webp 800w, https:\/\/www.goldminingmachine.com\/wp-content\/uploads\/2025\/12\/Vibrating-Screen3-300x225.webp 300w, https:\/\/www.goldminingmachine.com\/wp-content\/uploads\/2025\/12\/Vibrating-Screen3-768x576.webp 768w, https:\/\/www.goldminingmachine.com\/wp-content\/uploads\/2025\/12\/Vibrating-Screen3-16x12.webp 16w, https:\/\/www.goldminingmachine.com\/wp-content\/uploads\/2025\/12\/Vibrating-Screen3-624x468.webp 624w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/h2>\n<h2><strong>Equipo de procesamiento de oro eficiente, port\u00e1til e hidr\u00e1ulico<\/strong><\/h2>\n<h1><strong>Vista general del producto<\/strong><\/h1>\n<p>Nuestra m\u00e1quina de miner\u00eda de oro de pantalla vibrante es un <strong>Soluci\u00f3n completa y port\u00e1til<\/strong>\u00a0Para extracci\u00f3n de oro in situ. Dise\u00f1ado para flexibilidad y altas tasas de recuperaci\u00f3n, integra trituraci\u00f3n, cribado, lavado y enriquecimiento en una unidad compacta, ideal para operaciones mineras de peque\u00f1a a mediana escala.<\/p>\n<h1><strong>C\u00f3mo funciona<\/strong><\/h1>\n<ol>\n<li><strong>Alimentaci\u00f3n y trituraci\u00f3n<\/strong>: una excavcarga la materia prima en la pantalla vibr, donde se aplael mineral.<\/li>\n<li><strong>Lavado y filtrado<\/strong>: el material triturado se lava con agua a alta presi\u00f3n y se descarga desde la parte trasera. El tama\u00f1o de part\u00edcula de alimentaci\u00f3n var\u00eda de <strong>30-50cm<\/strong>; Part\u00edculas m\u00e1s peque\u00f1as (mezcla de agua y arena) caen a la segunda capa para su separaci\u00f3n.<\/li>\n<li><strong>Enriquecimiento de oro<\/strong>: la mezcla de agua y arena fluye en 3 escluindependientes regulables. Puede optimizar las tasas de recuperaci\u00f3n ajustel \u00e1ngulo delantero\/trasero y el equilibrio izquierdo\/derecho de la caja de esclupara adaptarse a diferentes terrenos y tipos de mineral.<\/li>\n<li><strong>F\u00e1cil mantenimiento y movilidad<\/strong>Las esteras de recogida (para la colecci\u00f3n de oro) se pueden retirar r\u00e1pidamente para el lavado. Al cambiar de ubicaci\u00f3n, simplemente arrastre la m\u00e1quina con una excavadora.<\/li>\n<\/ol>\n<h1><strong>Sistema de accion<\/strong><\/h1>\n<p>Esta m\u00e1quina de miner\u00eda de oro es <strong>100% impulsado hidr\u00e1ulicamente<\/strong>\u00a0(no requiere electricidad). El sistema hidr\u00e1ulico se conecta directamente al motor (sin correas ni cadenas), reduciendo los componentes de transmisi\u00f3n, reduciendo el consumo de combustible y minimizando el desgaste mec\u00e1nico.<\/p>\n<h1><strong>Especificaciones del modelo<\/strong><\/h1>\n<table style=\"width: 100%; border-collapse: collapse;\">\n<tbody><!-- \u7b2c\u4e00\u884c\uff1a\u6de1\u7070\u8272\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr style=\"background-color: #e0e0e0;\">\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\"><strong><span style=\"font-size: 14pt;\">par\u00e1metro<\/span><\/strong><\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\"><strong><span style=\"font-size: 14pt;\">Qrun-50<\/span><\/strong><\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\"><strong><span style=\"font-size: 14pt;\">Qrun-200<\/span><\/strong><\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\"><strong><span style=\"font-size: 14pt;\">Qrun-300<\/span><\/strong><\/td>\n<\/tr>\n<p><!-- \u5355\u6570\u884c\uff08\u7b2c2\u884c\uff0c\u6570\u636e\u884c\u7b2c1\u884c\uff09\uff1a#f0f0f0\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr style=\"background-color: #f0f0f0;\">\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">La longitud total<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">2,96 m<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">4,5 millones<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">5.27m<\/td>\n<\/tr>\n<p><!-- \u53cc\u6570\u884c\uff1a\u9ed8\u8ba4\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">La anchura total<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">0,9 millones<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">2.5m<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">2,9 millones<\/td>\n<\/tr>\n<p><!-- \u5355\u6570\u884c\uff08\u7b2c4\u884c\uff0c\u6570\u636e\u884c\u7b2c3\u884c\uff09\uff1a#f0f0f0\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr style=\"background-color: #f0f0f0;\">\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">Altura total<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">2<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">2,9 millones<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">3.35m<\/td>\n<\/tr>\n<p><!-- \u53cc\u6570\u884c\uff1a\u9ed8\u8ba4\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">Zona de agitaci\u00f3n<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">1\u33a1<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">4\u33a1<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">5.8\u33a1<\/td>\n<\/tr>\n<p><!-- \u5355\u6570\u884c\uff08\u7b2c6\u884c\uff0c\u6570\u636e\u884c\u7b2c5\u884c\uff09\uff1a#f0f0f0\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr style=\"background-color: #f0f0f0;\">\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">\u00c1rea de la caja de sacusacu<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">1.5\u33a1<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">6\u33a1<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">11\u33a1<\/td>\n<\/tr>\n<p><!-- \u53cc\u6570\u884c\uff1a\u9ed8\u8ba4\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">Potencia motriz<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">LA192<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">Yanmar (Japan)<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">\u2013<\/td>\n<\/tr>\n<p><!-- \u5355\u6570\u884c\uff08\u7b2c8\u884c\uff0c\u6570\u636e\u884c\u7b2c7\u884c\uff09\uff1a#f0f0f0\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr style=\"background-color: #f0f0f0;\">\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">Potencia \/RPM<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">14hp\/800r<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">19hp\/2400r<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">\u2013<\/td>\n<\/tr>\n<p><!-- \u53cc\u6570\u884c\uff1a\u9ed8\u8ba4\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">Bomba de agua<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">Diesel 4\u00d71 pulgada<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">150ZX40-32<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">\u2013<\/td>\n<\/tr>\n<p><!-- \u5355\u6570\u884c\uff08\u7b2c10\u884c\uff0c\u6570\u636e\u884c\u7b2c9\u884c\uff09\uff1a#f0f0f0\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr style=\"background-color: #f0f0f0;\">\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">Flujo\/cabeza<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">110m \u00b2 \/h, 32m<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">400m \u00b2 \/h, 32m<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">\u2013<\/td>\n<\/tr>\n<p><!-- \u53cc\u6570\u884c\uff1a\u9ed8\u8ba4\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">Equipado con poder<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">LA186F<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">Weichai<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">\u2013<\/td>\n<\/tr>\n<p><!-- \u5355\u6570\u884c\uff08\u7b2c12\u884c\uff0c\u6570\u636e\u884c\u7b2c11\u884c\uff09\uff1a#f0f0f0\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr style=\"background-color: #f0f0f0;\">\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">Motor de potencia nominal<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">9hp\/3600r<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">68kw\/1500r<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">\u2013<\/td>\n<\/tr>\n<p><!-- \u53cc\u6570\u884c\uff1a\u9ed8\u8ba4\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">rendimiento<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">50t\/h<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">200t\/h<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">300t\/h<\/td>\n<\/tr>\n<p><!-- \u5355\u6570\u884c\uff08\u7b2c14\u884c\uff0c\u6570\u636e\u884c\u7b2c13\u884c\uff09\uff1a#f0f0f0\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr style=\"background-color: #f0f0f0;\">\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">N\u00famero de empleados<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">1 persona<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">1 persona<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">\u2013<\/td>\n<\/tr>\n<p><!-- \u53cc\u6570\u884c\uff1a\u9ed8\u8ba4\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">Consumo de combustible<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">2.92L\/h<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">17.6L\/h<\/td>\n<td style=\"border: 1px solid #cccccc; height: 24px; width: 24.96%; padding: 4px;\">\u2013<\/td>\n<\/tr>\n<p><!-- \u5355\u6570\u884c\uff08\u7b2c16\u884c\uff0c\u6570\u636e\u884c\u7b2c15\u884c\uff09\uff1a#f0f0f0\u80cc\u666f + \u8fb9\u6846 --><\/p>\n<tr style=\"background-color: #f0f0f0;\">\n<td style=\"border: 1px solid #cccccc; height: 48px; width: 24.96%; padding: 4px;\">Puede equiparse con excavadora<\/td>\n<td style=\"border: 1px solid #cccccc; height: 48px; width: 24.96%; padding: 4px;\">15 toneladas<\/td>\n<td style=\"border: 1px solid #cccccc; height: 48px; width: 24.96%; padding: 4px;\">20-35 toneladas<\/td>\n<td style=\"border: 1px solid #cccccc; height: 48px; width: 24.96%; padding: 4px;\">\u2013<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h2><strong>\u00bfPor qu\u00e9 elegir nuestra m\u00e1quina de miner\u00eda de oro con pantalla vibr?<\/strong><\/h2>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-548\" src=\"http:\/\/www.goldminingmachine.com\/wp-content\/uploads\/2025\/12\/Vibrating-Screen5.webp\" alt=\"\" width=\"100%\" height=\"433\" srcset=\"https:\/\/www.goldminingmachine.com\/wp-content\/uploads\/2025\/12\/Vibrating-Screen5.webp 752w, https:\/\/www.goldminingmachine.com\/wp-content\/uploads\/2025\/12\/Vibrating-Screen5-300x173.webp 300w, https:\/\/www.goldminingmachine.com\/wp-content\/uploads\/2025\/12\/Vibrating-Screen5-18x10.webp 18w, https:\/\/www.goldminingmachine.com\/wp-content\/uploads\/2025\/12\/Vibrating-Screen5-624x359.webp 624w\" sizes=\"(max-width: 752px) 100vw, 752px\" \/><\/p>\n<div data-page-id=\"UzKzfYiVzdDTjJcEB9icOVhln2g\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\">\n<ul class=\"list-bullet1\">\n<li class=\"ace-line ace-line old-record-id-J7fLf0lVmd3wUBctEzZc5uifnCe\" data-list=\"bullet\">\n<div><strong>Dise\u00f1o port\u00e1til todo-en-uno:<\/strong> Una planta port\u00e1til completa que no requiere pantallas adicionales o esclusas, lista para su uso inmediatamente despu\u00e9s de desembalar.<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-ZJLkfnKJmdJkeIcL3tpcOA8UnpU\" data-list=\"bullet\">\n<div><strong>Accionamiento hidr\u00e1ulico Premium 100%:<\/strong> No se necesita electricidad; Equipado con sistema hidr\u00e1ulico DANFOSS USA para un rendimiento estable y fiable.<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-ZQlYfkMpWd02kEc4X5xcqhUzn3f\" data-list=\"bullet\">\n<div><strong>Superior recuperaci\u00f3n de oro:<\/strong> Tres esclusas independientes regulables con collares de caucho incorporados; La tasa de recuperaci\u00f3n de oro excede 95%, capaz de capturar oro fino hasta 200-300 malla.<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-K52afHqAyd698TcnK1Qcoawvn3c\" data-list=\"bullet\">\n<div><strong>Famosa marca de alfombras de caucho:<\/strong> Equipado con alfomde caucho de fama mundial espec\u00edficamente dise\u00f1ado para la recuperaci\u00f3n de oro de alta eficiencia.<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-XChrfITOQdpx8pc6ftQcsUffn8b\" data-list=\"bullet\">\n<div><strong>Port\u00e1til y Flexible:<\/strong> F\u00e1cil de reubicar con una excavadora, adaptable a diversos terrenos.<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-KvdzfheyEdlkHcclNWCcDa3gnce\" data-list=\"bullet\">\n<div><strong>Bajo mantenimiento y larga vida \u00fatil:<\/strong> El accionamiento hidr\u00e1ulico reduce el desgaste mec\u00e1nico; Las esteras de recogida desmontables simplila la limpieza, garantizando bajos costes de mantenimiento y una larga vida \u00fatil.<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-EP1vfOjIYdEBuecUKagcBIA2n6c\" data-list=\"bullet\">\n<div><strong>Seguro y fiable:<\/strong> Sin componentes el\u00e9ctricos, por lo que es ideal para sitios mineros remotos; Una construcci\u00f3n duradera garantiza un funcionamiento estable.<\/div>\n<\/li>\n<\/ul>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Equipo de procesamiento de oro port\u00e1til todo en uno con accionamiento hidr\u00e1ulico 100%, cajas de esclusa ajustindependientes y tasa de recuperaci\u00f3n 95%+ : f\u00e1cil de mover, de bajo mantenimiento y perfecto para sitios mineros remotos sin suministro el\u00e9ctrico. <\/p>","protected":false},"author":2,"featured_media":546,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,34],"tags":[],"class_list":["post-537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-products","category-vibrating-gold-mining-machinery"],"_links":{"self":[{"href":"https:\/\/www.goldminingmachine.com\/es\/wp-json\/wp\/v2\/posts\/537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goldminingmachine.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.goldminingmachine.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.goldminingmachine.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goldminingmachine.com\/es\/wp-json\/wp\/v2\/comments?post=537"}],"version-history":[{"count":10,"href":"https:\/\/www.goldminingmachine.com\/es\/wp-json\/wp\/v2\/posts\/537\/revisions"}],"predecessor-version":[{"id":558,"href":"https:\/\/www.goldminingmachine.com\/es\/wp-json\/wp\/v2\/posts\/537\/revisions\/558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.goldminingmachine.com\/es\/wp-json\/wp\/v2\/media\/546"}],"wp:attachment":[{"href":"https:\/\/www.goldminingmachine.com\/es\/wp-json\/wp\/v2\/media?parent=537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.goldminingmachine.com\/es\/wp-json\/wp\/v2\/categories?post=537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.goldminingmachine.com\/es\/wp-json\/wp\/v2\/tags?post=537"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}